{"id":7304,"date":"2024-12-16T12:47:13","date_gmt":"2024-12-16T11:47:13","guid":{"rendered":"https:\/\/winfield.lestaffdigital.fr\/?p=7304"},"modified":"2024-12-16T14:11:29","modified_gmt":"2024-12-16T13:11:29","slug":"theo-pourchaire-une-aventure-unique","status":"publish","type":"post","link":"https:\/\/winfield.lestaffdigital.fr\/fr\/theo-pourchaire-une-aventure-unique\/","title":{"rendered":"TH\u00c9O POURCHAIRE : \u00ab UNE AVENTURE UNIQUE ! \u00bb"},"content":{"rendered":"<p><strong>Sacr\u00e9 en Formule 2 au terme de la saison 2023, invit\u00e9 \u00e0 se produire en IndyCar Series en 2024, le pilote de Grasse est aujourd\u2019hui le fer de lance de la rel\u00e8ve fran\u00e7aise au plus niveau du sport automobile. <\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p>C\u2019\u00e9tait en f\u00e9vrier 2018, fort d\u2019un flatteur palmar\u00e8s en karting et membre de la FFSA Academy, le jeune Th\u00e9o, \u00e2g\u00e9 de 14 ans seulement, s\u2019appr\u00eatait \u00e0 op\u00e9rer le passage vers la monoplace. Il n\u2019avait alors aucune id\u00e9e de ce que repr\u00e9sentait l\u2019\u00e9cole \u00ab\u00a0Winfield\u00a0\u00bb. D\u2019elle, il savait peu de chose, juste qu\u2019elle avait une \u00ab\u00a0bonne r\u00e9putation\u00a0\u00bb.<\/p>\n<p>&nbsp;<\/p>\n<p>\u00ab\u00a0J\u2019ai commenc\u00e9 \u00e0 courir tr\u00e8s jeune et la Winfield m\u2019a servi de transition entre le kart et la monoplace, explique le pilote de Grasse. Ce fut une superbe exp\u00e9rience, tr\u00e8s intense. Du roulage, du simulateur, de la technique pour comprendre le fonctionnement d\u2019une auto, de l\u2019entrainement physique, du coaching, etc., c\u2019est incroyable tout ce que nous avons appris dans l\u2019ambiance studieuse mais d\u00e9contract\u00e9e du Campus Winfield. Ces trois jours d\u2019une grande richesse ont chang\u00e9 notre vie \u00e0 tout jamais. Je dis \u00ab\u00a0nous\u00a0\u00bb car beaucoup d\u2019autres \u00e9l\u00e8ves venaient comme moi de la FFSA Academy. On a vraiment tous acquis les bases du sport auto \u00e0 la Winfield.\u00a0\u00bb<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-7299\" src=\"https:\/\/winfield.lestaffdigital.fr\/wp-content\/uploads\/2024\/12\/VOLANT-WINFIELD-Morgan-MATHURIN-8667-300x200.jpg\" alt=\"\" width=\"668\" height=\"445\" srcset=\"https:\/\/winfield.lestaffdigital.fr\/wp-content\/uploads\/2024\/12\/VOLANT-WINFIELD-Morgan-MATHURIN-8667-300x200.jpg 300w, https:\/\/winfield.lestaffdigital.fr\/wp-content\/uploads\/2024\/12\/VOLANT-WINFIELD-Morgan-MATHURIN-8667-1024x683.jpg 1024w, https:\/\/winfield.lestaffdigital.fr\/wp-content\/uploads\/2024\/12\/VOLANT-WINFIELD-Morgan-MATHURIN-8667-768x512.jpg 768w, https:\/\/winfield.lestaffdigital.fr\/wp-content\/uploads\/2024\/12\/VOLANT-WINFIELD-Morgan-MATHURIN-8667-1536x1024.jpg 1536w, https:\/\/winfield.lestaffdigital.fr\/wp-content\/uploads\/2024\/12\/VOLANT-WINFIELD-Morgan-MATHURIN-8667-2048x1366.jpg 2048w, https:\/\/winfield.lestaffdigital.fr\/wp-content\/uploads\/2024\/12\/VOLANT-WINFIELD-Morgan-MATHURIN-8667-600x400.jpg 600w\" sizes=\"auto, (max-width: 668px) 100vw, 668px\" \/><\/p>\n<p><em>Th\u00e9o Pourchaire durant le Troph\u00e9e Winfield 2018 au Circuit Paul Ricard<\/em><\/p>\n<p>&nbsp;<\/p>\n<p>Pass\u00e9 du karting \u00e0 la monoplace n\u2019est pas anodin car il s\u2019agit de deux mondes assez diff\u00e9rents, surtout pour un adolescent. \u00ab\u00a0J\u2019avais 14 ans en 2018 et j\u2019\u00e9tais trop jeune pour participer au Volant, se souvient-il. Par contre, j\u2019ai remport\u00e9 le \u00ab\u00a0Troph\u00e9e\u00a0\u00bb r\u00e9serv\u00e9 au moins de 15 ans qui m\u2019a permis d\u2019obtenir une bourse pour aider \u00e0 financer mes d\u00e9buts en championnat de France F4.\u00a0\u00bb<\/p>\n<p>&nbsp;<\/p>\n<p>Laur\u00e9at de la cat\u00e9gorie \u00ab\u00a0Junior\u00a0\u00bb la m\u00eame ann\u00e9e, il allait enchainer les saisons suivantes avec le titre en F4 Allemagne, puis celui de vice-champion de F3 FIA avant de passer \u00e0 la F2. Vice-champion en 2022, il faisait ses premi\u00e8res armes en F1 chez Alfa-Romeo\/Sauber en qualit\u00e9 de pilote d\u2019essais. Sacr\u00e9 Champion F2 l\u2019ann\u00e9e suivante, il voyait s\u2019ouvrir les portes du puissant championnat IndyCar nord-am\u00e9ricain en 2024, puis ensuite du mythique championnat du monde d\u2019endurance avec Peugeot.<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-7301\" src=\"https:\/\/winfield.lestaffdigital.fr\/wp-content\/uploads\/2024\/12\/CPR_F2_DL-6990-300x200.jpg\" alt=\"\" width=\"668\" height=\"445\" srcset=\"https:\/\/winfield.lestaffdigital.fr\/wp-content\/uploads\/2024\/12\/CPR_F2_DL-6990-300x200.jpg 300w, https:\/\/winfield.lestaffdigital.fr\/wp-content\/uploads\/2024\/12\/CPR_F2_DL-6990-1024x683.jpg 1024w, https:\/\/winfield.lestaffdigital.fr\/wp-content\/uploads\/2024\/12\/CPR_F2_DL-6990-768x512.jpg 768w, https:\/\/winfield.lestaffdigital.fr\/wp-content\/uploads\/2024\/12\/CPR_F2_DL-6990-1536x1024.jpg 1536w, https:\/\/winfield.lestaffdigital.fr\/wp-content\/uploads\/2024\/12\/CPR_F2_DL-6990-2048x1365.jpg 2048w, https:\/\/winfield.lestaffdigital.fr\/wp-content\/uploads\/2024\/12\/CPR_F2_DL-6990-600x400.jpg 600w\" sizes=\"auto, (max-width: 668px) 100vw, 668px\" \/><\/p>\n<p><em>Th\u00e9o Pourchaire pendant la course de Formule 2 en 2018 Circuit Paul Ricard<\/em><\/p>\n<p>&nbsp;<\/p>\n<p>\u00ab\u00a0Sans ce magnifique tremplin que fut la Winfield, je ne suis pas s\u00fbr que j\u2019aurais eu le m\u00eame parcours en auto. Ce fut une aventure unique qui m\u2019a marqu\u00e9, et une fiert\u00e9 de rejoindre la liste prestigieuse de pilotes qui sont pass\u00e9s par l\u2019\u00e9cole.\u00a0\u00bb Car entre-temps, il avait d\u00e9couvert les 60 ans d\u2019histoire de l\u2019\u00e9cole.<\/p>\n<p>&nbsp;<\/p>\n<p>Cr\u00e9dits photos : Morgan Mathurin \/ FIA F2<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sacr\u00e9 en Formule 2 au terme de la saison 2023, invit\u00e9 \u00e0 se produire en IndyCar Series en 2024, le pilote de Grasse est aujourd\u2019hui le fer de lance de la rel\u00e8ve fran\u00e7aise au plus niveau du sport automobile. \u00a0 C\u2019\u00e9tait en f\u00e9vrier 2018, fort d\u2019un flatteur palmar\u00e8s en karting et membre de la FFSA [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":7297,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[40],"tags":[],"class_list":["post-7304","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-non-classifiee-fr"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>TH\u00c9O POURCHAIRE : \u00ab UNE AVENTURE UNIQUE ! \u00bb<\/title>\n<meta name=\"description\" content=\"Th\u00e9o Pourchaire, sacr\u00e9 Champion F2 en 2023, raconte son ascension de Winfield aux d\u00e9fis de l&#039;IndyCar et du WEC en 2024.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/winfield.lestaffdigital.fr\/fr\/theo-pourchaire-une-aventure-unique\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"TH\u00c9O POURCHAIRE : \u00ab UNE AVENTURE UNIQUE ! \u00bb\" \/>\n<meta property=\"og:description\" content=\"Th\u00e9o Pourchaire, sacr\u00e9 Champion F2 en 2023, raconte son ascension de Winfield aux d\u00e9fis de l&#039;IndyCar et du WEC en 2024.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/winfield.lestaffdigital.fr\/fr\/theo-pourchaire-une-aventure-unique\/\" \/>\n<meta property=\"og:site_name\" content=\"Winfield\" \/>\n<meta property=\"article:published_time\" content=\"2024-12-16T11:47:13+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-12-16T13:11:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/winfield.lestaffdigital.fr\/wp-content\/uploads\/2024\/12\/POURCHAIRE.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"463\" \/>\n\t<meta property=\"og:image:height\" content=\"718\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"alexis.miclo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"alexis.miclo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/winfield.lestaffdigital.fr\\\/fr\\\/theo-pourchaire-une-aventure-unique\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/winfield.lestaffdigital.fr\\\/fr\\\/theo-pourchaire-une-aventure-unique\\\/\"},\"author\":{\"name\":\"alexis.miclo\",\"@id\":\"https:\\\/\\\/winfield.lestaffdigital.fr\\\/fr\\\/#\\\/schema\\\/person\\\/866926d74c43f8fe3600a1aabdb95e7a\"},\"headline\":\"TH\u00c9O POURCHAIRE : \u00ab UNE AVENTURE UNIQUE ! \u00bb\",\"datePublished\":\"2024-12-16T11:47:13+00:00\",\"dateModified\":\"2024-12-16T13:11:29+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/winfield.lestaffdigital.fr\\\/fr\\\/theo-pourchaire-une-aventure-unique\\\/\"},\"wordCount\":487,\"publisher\":{\"@id\":\"https:\\\/\\\/winfield.lestaffdigital.fr\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/winfield.lestaffdigital.fr\\\/fr\\\/theo-pourchaire-une-aventure-unique\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/winfield.lestaffdigital.fr\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/POURCHAIRE.jpg\",\"articleSection\":[\"Non classifi\u00e9(e)\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/winfield.lestaffdigital.fr\\\/fr\\\/theo-pourchaire-une-aventure-unique\\\/\",\"url\":\"https:\\\/\\\/winfield.lestaffdigital.fr\\\/fr\\\/theo-pourchaire-une-aventure-unique\\\/\",\"name\":\"TH\u00c9O POURCHAIRE : \u00ab UNE AVENTURE UNIQUE ! \u00bb\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/winfield.lestaffdigital.fr\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/winfield.lestaffdigital.fr\\\/fr\\\/theo-pourchaire-une-aventure-unique\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/winfield.lestaffdigital.fr\\\/fr\\\/theo-pourchaire-une-aventure-unique\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/winfield.lestaffdigital.fr\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/POURCHAIRE.jpg\",\"datePublished\":\"2024-12-16T11:47:13+00:00\",\"dateModified\":\"2024-12-16T13:11:29+00:00\",\"description\":\"Th\u00e9o Pourchaire, sacr\u00e9 Champion F2 en 2023, raconte son ascension de Winfield aux d\u00e9fis de l'IndyCar et du WEC en 2024.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/winfield.lestaffdigital.fr\\\/fr\\\/theo-pourchaire-une-aventure-unique\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/winfield.lestaffdigital.fr\\\/fr\\\/theo-pourchaire-une-aventure-unique\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/winfield.lestaffdigital.fr\\\/fr\\\/theo-pourchaire-une-aventure-unique\\\/#primaryimage\",\"url\":\"https:\\\/\\\/winfield.lestaffdigital.fr\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/POURCHAIRE.jpg\",\"contentUrl\":\"https:\\\/\\\/winfield.lestaffdigital.fr\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/POURCHAIRE.jpg\",\"width\":463,\"height\":718},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/winfield.lestaffdigital.fr\\\/fr\\\/theo-pourchaire-une-aventure-unique\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/winfield.lestaffdigital.fr\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"TH\u00c9O POURCHAIRE : \u00ab UNE AVENTURE UNIQUE ! \u00bb\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/winfield.lestaffdigital.fr\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/winfield.lestaffdigital.fr\\\/fr\\\/\",\"name\":\"Winfield\",\"description\":\"Circuit automobile &amp; \u00c9cole de pilotage\",\"publisher\":{\"@id\":\"https:\\\/\\\/winfield.lestaffdigital.fr\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/winfield.lestaffdigital.fr\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/winfield.lestaffdigital.fr\\\/fr\\\/#organization\",\"name\":\"Winfield\",\"url\":\"https:\\\/\\\/winfield.lestaffdigital.fr\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/winfield.lestaffdigital.fr\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/winfield.lestaffdigital.fr\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/Groupe-452.png\",\"contentUrl\":\"https:\\\/\\\/winfield.lestaffdigital.fr\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/Groupe-452.png\",\"width\":186,\"height\":72,\"caption\":\"Winfield\"},\"image\":{\"@id\":\"https:\\\/\\\/winfield.lestaffdigital.fr\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/winfield.lestaffdigital.fr\\\/fr\\\/#\\\/schema\\\/person\\\/866926d74c43f8fe3600a1aabdb95e7a\",\"name\":\"alexis.miclo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fa6692f97645aafd83b38b0cad6c2a1962f7fe10d16c523b9aa454d77c43f9fa?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fa6692f97645aafd83b38b0cad6c2a1962f7fe10d16c523b9aa454d77c43f9fa?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fa6692f97645aafd83b38b0cad6c2a1962f7fe10d16c523b9aa454d77c43f9fa?s=96&d=mm&r=g\",\"caption\":\"alexis.miclo\"},\"url\":\"https:\\\/\\\/winfield.lestaffdigital.fr\\\/fr\\\/author\\\/alexis-miclo\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"TH\u00c9O POURCHAIRE : \u00ab UNE AVENTURE UNIQUE ! \u00bb","description":"Th\u00e9o Pourchaire, sacr\u00e9 Champion F2 en 2023, raconte son ascension de Winfield aux d\u00e9fis de l'IndyCar et du WEC en 2024.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/winfield.lestaffdigital.fr\/fr\/theo-pourchaire-une-aventure-unique\/","og_locale":"fr_FR","og_type":"article","og_title":"TH\u00c9O POURCHAIRE : \u00ab UNE AVENTURE UNIQUE ! \u00bb","og_description":"Th\u00e9o Pourchaire, sacr\u00e9 Champion F2 en 2023, raconte son ascension de Winfield aux d\u00e9fis de l'IndyCar et du WEC en 2024.","og_url":"https:\/\/winfield.lestaffdigital.fr\/fr\/theo-pourchaire-une-aventure-unique\/","og_site_name":"Winfield","article_published_time":"2024-12-16T11:47:13+00:00","article_modified_time":"2024-12-16T13:11:29+00:00","og_image":[{"width":463,"height":718,"url":"https:\/\/winfield.lestaffdigital.fr\/wp-content\/uploads\/2024\/12\/POURCHAIRE.jpg","type":"image\/jpeg"}],"author":"alexis.miclo","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"alexis.miclo","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/winfield.lestaffdigital.fr\/fr\/theo-pourchaire-une-aventure-unique\/#article","isPartOf":{"@id":"https:\/\/winfield.lestaffdigital.fr\/fr\/theo-pourchaire-une-aventure-unique\/"},"author":{"name":"alexis.miclo","@id":"https:\/\/winfield.lestaffdigital.fr\/fr\/#\/schema\/person\/866926d74c43f8fe3600a1aabdb95e7a"},"headline":"TH\u00c9O POURCHAIRE : \u00ab UNE AVENTURE UNIQUE ! \u00bb","datePublished":"2024-12-16T11:47:13+00:00","dateModified":"2024-12-16T13:11:29+00:00","mainEntityOfPage":{"@id":"https:\/\/winfield.lestaffdigital.fr\/fr\/theo-pourchaire-une-aventure-unique\/"},"wordCount":487,"publisher":{"@id":"https:\/\/winfield.lestaffdigital.fr\/fr\/#organization"},"image":{"@id":"https:\/\/winfield.lestaffdigital.fr\/fr\/theo-pourchaire-une-aventure-unique\/#primaryimage"},"thumbnailUrl":"https:\/\/winfield.lestaffdigital.fr\/wp-content\/uploads\/2024\/12\/POURCHAIRE.jpg","articleSection":["Non classifi\u00e9(e)"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/winfield.lestaffdigital.fr\/fr\/theo-pourchaire-une-aventure-unique\/","url":"https:\/\/winfield.lestaffdigital.fr\/fr\/theo-pourchaire-une-aventure-unique\/","name":"TH\u00c9O POURCHAIRE : \u00ab UNE AVENTURE UNIQUE ! \u00bb","isPartOf":{"@id":"https:\/\/winfield.lestaffdigital.fr\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/winfield.lestaffdigital.fr\/fr\/theo-pourchaire-une-aventure-unique\/#primaryimage"},"image":{"@id":"https:\/\/winfield.lestaffdigital.fr\/fr\/theo-pourchaire-une-aventure-unique\/#primaryimage"},"thumbnailUrl":"https:\/\/winfield.lestaffdigital.fr\/wp-content\/uploads\/2024\/12\/POURCHAIRE.jpg","datePublished":"2024-12-16T11:47:13+00:00","dateModified":"2024-12-16T13:11:29+00:00","description":"Th\u00e9o Pourchaire, sacr\u00e9 Champion F2 en 2023, raconte son ascension de Winfield aux d\u00e9fis de l'IndyCar et du WEC en 2024.","breadcrumb":{"@id":"https:\/\/winfield.lestaffdigital.fr\/fr\/theo-pourchaire-une-aventure-unique\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/winfield.lestaffdigital.fr\/fr\/theo-pourchaire-une-aventure-unique\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/winfield.lestaffdigital.fr\/fr\/theo-pourchaire-une-aventure-unique\/#primaryimage","url":"https:\/\/winfield.lestaffdigital.fr\/wp-content\/uploads\/2024\/12\/POURCHAIRE.jpg","contentUrl":"https:\/\/winfield.lestaffdigital.fr\/wp-content\/uploads\/2024\/12\/POURCHAIRE.jpg","width":463,"height":718},{"@type":"BreadcrumbList","@id":"https:\/\/winfield.lestaffdigital.fr\/fr\/theo-pourchaire-une-aventure-unique\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/winfield.lestaffdigital.fr\/fr\/"},{"@type":"ListItem","position":2,"name":"TH\u00c9O POURCHAIRE : \u00ab UNE AVENTURE UNIQUE ! \u00bb"}]},{"@type":"WebSite","@id":"https:\/\/winfield.lestaffdigital.fr\/fr\/#website","url":"https:\/\/winfield.lestaffdigital.fr\/fr\/","name":"Winfield","description":"Circuit automobile &amp; \u00c9cole de pilotage","publisher":{"@id":"https:\/\/winfield.lestaffdigital.fr\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/winfield.lestaffdigital.fr\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/winfield.lestaffdigital.fr\/fr\/#organization","name":"Winfield","url":"https:\/\/winfield.lestaffdigital.fr\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/winfield.lestaffdigital.fr\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/winfield.lestaffdigital.fr\/wp-content\/uploads\/2023\/03\/Groupe-452.png","contentUrl":"https:\/\/winfield.lestaffdigital.fr\/wp-content\/uploads\/2023\/03\/Groupe-452.png","width":186,"height":72,"caption":"Winfield"},"image":{"@id":"https:\/\/winfield.lestaffdigital.fr\/fr\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/winfield.lestaffdigital.fr\/fr\/#\/schema\/person\/866926d74c43f8fe3600a1aabdb95e7a","name":"alexis.miclo","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/fa6692f97645aafd83b38b0cad6c2a1962f7fe10d16c523b9aa454d77c43f9fa?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/fa6692f97645aafd83b38b0cad6c2a1962f7fe10d16c523b9aa454d77c43f9fa?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fa6692f97645aafd83b38b0cad6c2a1962f7fe10d16c523b9aa454d77c43f9fa?s=96&d=mm&r=g","caption":"alexis.miclo"},"url":"https:\/\/winfield.lestaffdigital.fr\/fr\/author\/alexis-miclo\/"}]}},"_links":{"self":[{"href":"https:\/\/winfield.lestaffdigital.fr\/fr\/wp-json\/wp\/v2\/posts\/7304","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/winfield.lestaffdigital.fr\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/winfield.lestaffdigital.fr\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/winfield.lestaffdigital.fr\/fr\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/winfield.lestaffdigital.fr\/fr\/wp-json\/wp\/v2\/comments?post=7304"}],"version-history":[{"count":2,"href":"https:\/\/winfield.lestaffdigital.fr\/fr\/wp-json\/wp\/v2\/posts\/7304\/revisions"}],"predecessor-version":[{"id":7320,"href":"https:\/\/winfield.lestaffdigital.fr\/fr\/wp-json\/wp\/v2\/posts\/7304\/revisions\/7320"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/winfield.lestaffdigital.fr\/fr\/wp-json\/wp\/v2\/media\/7297"}],"wp:attachment":[{"href":"https:\/\/winfield.lestaffdigital.fr\/fr\/wp-json\/wp\/v2\/media?parent=7304"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/winfield.lestaffdigital.fr\/fr\/wp-json\/wp\/v2\/categories?post=7304"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/winfield.lestaffdigital.fr\/fr\/wp-json\/wp\/v2\/tags?post=7304"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}