{"id":6878,"date":"2024-10-24T11:00:38","date_gmt":"2024-10-24T09:00:38","guid":{"rendered":"https:\/\/winfield.lestaffdigital.fr\/?p=6878"},"modified":"2024-10-24T11:11:43","modified_gmt":"2024-10-24T09:11:43","slug":"damon-hill-winfield-ma-donne-le-gout-de-lauto","status":"publish","type":"post","link":"https:\/\/winfield.lestaffdigital.fr\/fr\/damon-hill-winfield-ma-donne-le-gout-de-lauto\/","title":{"rendered":"DAMON HILL : \u00ab WINFIELD M&rsquo;A DONN\u00c9 LE GO\u00dbT DE L&rsquo;AUTO ! \u00bb"},"content":{"rendered":"<p>&nbsp;<\/p>\n<p><strong>Fou de moto, Damon Hill d\u00e9barque \u00e0 Magny-Cours en 1983 sans autre ambition que de s\u2019amuser. Il ne le sait pas encore, mais sa vie est sur le point de basculer.<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>Non ! Quand sa m\u00e8re Bette lui annonce un jour que Mike Knight aimerait l\u2019accueillir \u00e0 Magny-Cours, Damon lui fait bien comprendre qu\u2019il ne faut pas compter sur lui. \u00ab Je n\u2019\u00e9tais absolument pas int\u00e9ress\u00e9 par les voitures de course, note celui qui n\u2019est alors que le fils du regrett\u00e9 double champion du monde et seul pilote \u00e0 avoir remport\u00e9 la Triple Couronne Graham Hill. Ma vie, c\u2019\u00e9tait les motos. Je ne connaissais presque rien au sport automobile, \u00e0 part quelques notions sur la Formule 1. Un jour, ma m\u00e8re est venue me dire qu&rsquo;il existait une \u00e9cole en France, et qu&rsquo;un certain Mike \u00e9tait pr\u00eat \u00e0 me faire d\u00e9couvrir la monoplace si cela m&rsquo;int\u00e9ressait. Mais \u00e7a ne m&rsquo;int\u00e9ressait pas. Je lui ai r\u00e9pondu que je finan\u00e7ais d\u00e9j\u00e0 ma moto et que je n&rsquo;avais pas d&rsquo;argent \u00e0 d\u00e9penser en plus. Elle m\u2019a alors dit qu\u2019il prenait tout \u00e0 sa charge. Du coup, j\u2019ai dit pourquoi pas ! Honn\u00eatement, je n\u2019ai jamais trop su qui a contact\u00e9 l\u2019autre en premier : ma m\u00e8re qui souhaitait me voir stopper la moto ou Mike qui cherchait \u00e0 donner une dimension plus internationale \u00e0 son \u00e9cole \u2026 \u00bb<\/p>\n<p>&nbsp;<\/p>\n<p>Quelques temps plus tard, Damon se retrouve dans un avion en compagnie d\u2019autres \u00e9l\u00e8ves et un journaliste du magazine Cars &amp; Car Conversion. \u00ab Tout le monde parlait du Docteur Jonathan Palmer qui gagnait en Formule 2 mais je n\u2019avais pas la moindre id\u00e9e de qui cela pouvait bien \u00eatre, s\u2019amuse aujourd\u2019hui encore le britannique. Je suis arriv\u00e9 \u00e0 Magny-Cours avec l\u2019\u00e9tat d\u2019esprit du type qui vient s\u2019amuser. Rien de plus. Je n\u2019avais aucune ambition. J&rsquo;ai pass\u00e9 la soir\u00e9e avec le journaliste \u00e0 essayer de trouver une bi\u00e8re. Nous \u00e9tions dans un petit bar, au c\u0153ur d&rsquo;un village \u00e9loign\u00e9 en France, o\u00f9 le patron ne servait la bi\u00e8re que dans de petits verres, alors que nous demandions une pinte. C&rsquo;\u00e9tait \u00e9pique !<\/p>\n<p>&nbsp;<\/p>\n<p>Le lendemain, Damon n\u2019est pas plus impressionn\u00e9 par l\u2019\u00e9cole que par l\u2019estaminet. \u00ab Ils nous ont appris \u00e0 passer les vitesses, \u00e0 freiner, \u00e0 slalomer entre les c\u00f4nes, ce genre de choses qui m\u2019a vite ennuy\u00e9. Et puis, finalement, nous sommes arriv\u00e9s au point o\u00f9 l\u2019on pouvait faire des tours. L\u00e0, tout a chang\u00e9. C\u2019\u00e9tait ces m\u00eames tours sur lesquels nous \u00e9tions jug\u00e9s. \u00bb<\/p>\n<p>&nbsp;<\/p>\n<p>Si le futur champion du monde de Formule 1 rentre au Royaume Uni ravit de son exp\u00e9rience, ce n\u2019est pas non plus la r\u00e9v\u00e9lation. \u00ab J\u2019avais pass\u00e9 du bon temps, mais je n\u2019\u00e9tais pas tomb\u00e9 amoureux du sport auto. Autant dire que je n\u2019ai pas \u00e9t\u00e9 peu surpris de me retrouver qualifi\u00e9 pour la phase finale. Pour moi, c\u2019\u00e9tait plus un coup de pub pour l\u2019\u00e9cole. \u00bb<\/p>\n<p>&nbsp;<\/p>\n<p>Qu\u2019importe, il s\u2019y rend mais avec de tout autre ambition cette fois. \u00ab S\u2019ils voulaient que je revienne, ils allaient voir. Cette fois, comme j\u2019\u00e9tais d\u2019une nature comp\u00e9titive, je voulais gagner. Je suis arriv\u00e9 avec une autre d\u00e9termination, mais j\u2019en ai trop fait. J\u2019ai trop pouss\u00e9. Perdre m\u2019a contrari\u00e9, mais \u00e7a a commenc\u00e9 \u00e0 me d\u00e9manger. Je me suis demand\u00e9 si, finalement, je ne devrais pas tenter ma chance. Cet \u00e9chec a sans doute \u00e9t\u00e9 la meilleure chose qui pouvait m\u2019arriver. \u00bb<\/p>\n<p>&nbsp;<\/p>\n<p>Le passage de la moto \u00e0 l\u2019auto est alors facilit\u00e9 par John Webb, patron de Brand Hatch, qui lui propose son aide mais, l\u00e0 encore, c\u2019est l\u2019aspect publicitaire qui prime. \u00ab J\u2019\u00e9tais na\u00eff, et je d\u00e9vorais le magazine Autosport pour tenter de comprendre ce monde qui m\u2019\u00e9tait totalement \u00e9tranger en d\u00e9pit de ma filiation. Quand j\u2019ai commenc\u00e9 \u00e0 courir, j\u2019\u00e9tais au niveau z\u00e9ro. \u00bb<\/p>\n<p>&nbsp;<\/p>\n<p>L\u2019histoire \u00e9tait malgr\u00e9 tout en marche. \u00ab Winfield, conclut-il, m\u2019a donn\u00e9 le go\u00fbt de l\u2019auto ! \u00bb<\/p>\n<p>&nbsp;<\/p>\n<p><em>Cr\u00e9dits photos : Bernard Asset<br \/>\n<\/em><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; Fou de moto, Damon Hill d\u00e9barque \u00e0 Magny-Cours en 1983 sans autre ambition que de s\u2019amuser. Il ne le sait pas encore, mais sa vie est sur le point de basculer. &nbsp; Non ! Quand sa m\u00e8re Bette lui annonce un jour que Mike Knight aimerait l\u2019accueillir \u00e0 Magny-Cours, Damon lui fait bien comprendre [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":6875,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[40],"tags":[],"class_list":["post-6878","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-non-classifiee-fr"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>DAMON HILL : \u00ab WINFIELD M&#039;A DONN\u00c9 LE GO\u00dbT DE L&#039;AUTO ! \u00bb<\/title>\n<meta name=\"description\" content=\"En 1983, Damon Hill d\u00e9couvre la monoplace \u00e0 l&#039;\u00e9cole Winfield, un tournant qui l&#039;am\u00e8ne \u00e0 d\u00e9laisser la moto pour le sport automobile.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/winfield.lestaffdigital.fr\/fr\/damon-hill-winfield-ma-donne-le-gout-de-lauto\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"DAMON HILL : \u00ab WINFIELD M&#039;A DONN\u00c9 LE GO\u00dbT DE L&#039;AUTO ! \u00bb\" \/>\n<meta property=\"og:description\" content=\"En 1983, Damon Hill d\u00e9couvre la monoplace \u00e0 l&#039;\u00e9cole Winfield, un tournant qui l&#039;am\u00e8ne \u00e0 d\u00e9laisser la moto pour le sport automobile.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/winfield.lestaffdigital.fr\/fr\/damon-hill-winfield-ma-donne-le-gout-de-lauto\/\" \/>\n<meta property=\"og:site_name\" content=\"Winfield\" \/>\n<meta property=\"article:published_time\" content=\"2024-10-24T09:00:38+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-10-24T09:11:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/winfield.lestaffdigital.fr\/wp-content\/uploads\/2024\/10\/Template-Article-WRS_2023-copie.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"463\" \/>\n\t<meta property=\"og:image:height\" content=\"718\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"alexis.miclo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"alexis.miclo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/winfield.lestaffdigital.fr\\\/fr\\\/damon-hill-winfield-ma-donne-le-gout-de-lauto\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/winfield.lestaffdigital.fr\\\/fr\\\/damon-hill-winfield-ma-donne-le-gout-de-lauto\\\/\"},\"author\":{\"name\":\"alexis.miclo\",\"@id\":\"https:\\\/\\\/winfield.lestaffdigital.fr\\\/fr\\\/#\\\/schema\\\/person\\\/866926d74c43f8fe3600a1aabdb95e7a\"},\"headline\":\"DAMON HILL : \u00ab WINFIELD M&rsquo;A DONN\u00c9 LE GO\u00dbT DE L&rsquo;AUTO ! \u00bb\",\"datePublished\":\"2024-10-24T09:00:38+00:00\",\"dateModified\":\"2024-10-24T09:11:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/winfield.lestaffdigital.fr\\\/fr\\\/damon-hill-winfield-ma-donne-le-gout-de-lauto\\\/\"},\"wordCount\":722,\"publisher\":{\"@id\":\"https:\\\/\\\/winfield.lestaffdigital.fr\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/winfield.lestaffdigital.fr\\\/fr\\\/damon-hill-winfield-ma-donne-le-gout-de-lauto\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/winfield.lestaffdigital.fr\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/Template-Article-WRS_2023-copie.jpg\",\"articleSection\":[\"Non classifi\u00e9(e)\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/winfield.lestaffdigital.fr\\\/fr\\\/damon-hill-winfield-ma-donne-le-gout-de-lauto\\\/\",\"url\":\"https:\\\/\\\/winfield.lestaffdigital.fr\\\/fr\\\/damon-hill-winfield-ma-donne-le-gout-de-lauto\\\/\",\"name\":\"DAMON HILL : \u00ab WINFIELD M'A DONN\u00c9 LE GO\u00dbT DE L'AUTO ! \u00bb\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/winfield.lestaffdigital.fr\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/winfield.lestaffdigital.fr\\\/fr\\\/damon-hill-winfield-ma-donne-le-gout-de-lauto\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/winfield.lestaffdigital.fr\\\/fr\\\/damon-hill-winfield-ma-donne-le-gout-de-lauto\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/winfield.lestaffdigital.fr\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/Template-Article-WRS_2023-copie.jpg\",\"datePublished\":\"2024-10-24T09:00:38+00:00\",\"dateModified\":\"2024-10-24T09:11:43+00:00\",\"description\":\"En 1983, Damon Hill d\u00e9couvre la monoplace \u00e0 l'\u00e9cole Winfield, un tournant qui l'am\u00e8ne \u00e0 d\u00e9laisser la moto pour le sport automobile.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/winfield.lestaffdigital.fr\\\/fr\\\/damon-hill-winfield-ma-donne-le-gout-de-lauto\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/winfield.lestaffdigital.fr\\\/fr\\\/damon-hill-winfield-ma-donne-le-gout-de-lauto\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/winfield.lestaffdigital.fr\\\/fr\\\/damon-hill-winfield-ma-donne-le-gout-de-lauto\\\/#primaryimage\",\"url\":\"https:\\\/\\\/winfield.lestaffdigital.fr\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/Template-Article-WRS_2023-copie.jpg\",\"contentUrl\":\"https:\\\/\\\/winfield.lestaffdigital.fr\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/Template-Article-WRS_2023-copie.jpg\",\"width\":463,\"height\":718},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/winfield.lestaffdigital.fr\\\/fr\\\/damon-hill-winfield-ma-donne-le-gout-de-lauto\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/winfield.lestaffdigital.fr\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"DAMON HILL : \u00ab WINFIELD M&rsquo;A DONN\u00c9 LE GO\u00dbT DE L&rsquo;AUTO ! \u00bb\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/winfield.lestaffdigital.fr\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/winfield.lestaffdigital.fr\\\/fr\\\/\",\"name\":\"Winfield\",\"description\":\"Circuit automobile &amp; \u00c9cole de pilotage\",\"publisher\":{\"@id\":\"https:\\\/\\\/winfield.lestaffdigital.fr\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/winfield.lestaffdigital.fr\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/winfield.lestaffdigital.fr\\\/fr\\\/#organization\",\"name\":\"Winfield\",\"url\":\"https:\\\/\\\/winfield.lestaffdigital.fr\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/winfield.lestaffdigital.fr\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/winfield.lestaffdigital.fr\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/Groupe-452.png\",\"contentUrl\":\"https:\\\/\\\/winfield.lestaffdigital.fr\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/Groupe-452.png\",\"width\":186,\"height\":72,\"caption\":\"Winfield\"},\"image\":{\"@id\":\"https:\\\/\\\/winfield.lestaffdigital.fr\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/winfield.lestaffdigital.fr\\\/fr\\\/#\\\/schema\\\/person\\\/866926d74c43f8fe3600a1aabdb95e7a\",\"name\":\"alexis.miclo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fa6692f97645aafd83b38b0cad6c2a1962f7fe10d16c523b9aa454d77c43f9fa?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fa6692f97645aafd83b38b0cad6c2a1962f7fe10d16c523b9aa454d77c43f9fa?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fa6692f97645aafd83b38b0cad6c2a1962f7fe10d16c523b9aa454d77c43f9fa?s=96&d=mm&r=g\",\"caption\":\"alexis.miclo\"},\"url\":\"https:\\\/\\\/winfield.lestaffdigital.fr\\\/fr\\\/author\\\/alexis-miclo\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"DAMON HILL : \u00ab WINFIELD M'A DONN\u00c9 LE GO\u00dbT DE L'AUTO ! \u00bb","description":"En 1983, Damon Hill d\u00e9couvre la monoplace \u00e0 l'\u00e9cole Winfield, un tournant qui l'am\u00e8ne \u00e0 d\u00e9laisser la moto pour le sport automobile.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/winfield.lestaffdigital.fr\/fr\/damon-hill-winfield-ma-donne-le-gout-de-lauto\/","og_locale":"fr_FR","og_type":"article","og_title":"DAMON HILL : \u00ab WINFIELD M'A DONN\u00c9 LE GO\u00dbT DE L'AUTO ! \u00bb","og_description":"En 1983, Damon Hill d\u00e9couvre la monoplace \u00e0 l'\u00e9cole Winfield, un tournant qui l'am\u00e8ne \u00e0 d\u00e9laisser la moto pour le sport automobile.","og_url":"https:\/\/winfield.lestaffdigital.fr\/fr\/damon-hill-winfield-ma-donne-le-gout-de-lauto\/","og_site_name":"Winfield","article_published_time":"2024-10-24T09:00:38+00:00","article_modified_time":"2024-10-24T09:11:43+00:00","og_image":[{"width":463,"height":718,"url":"https:\/\/winfield.lestaffdigital.fr\/wp-content\/uploads\/2024\/10\/Template-Article-WRS_2023-copie.jpg","type":"image\/jpeg"}],"author":"alexis.miclo","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"alexis.miclo","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/winfield.lestaffdigital.fr\/fr\/damon-hill-winfield-ma-donne-le-gout-de-lauto\/#article","isPartOf":{"@id":"https:\/\/winfield.lestaffdigital.fr\/fr\/damon-hill-winfield-ma-donne-le-gout-de-lauto\/"},"author":{"name":"alexis.miclo","@id":"https:\/\/winfield.lestaffdigital.fr\/fr\/#\/schema\/person\/866926d74c43f8fe3600a1aabdb95e7a"},"headline":"DAMON HILL : \u00ab WINFIELD M&rsquo;A DONN\u00c9 LE GO\u00dbT DE L&rsquo;AUTO ! \u00bb","datePublished":"2024-10-24T09:00:38+00:00","dateModified":"2024-10-24T09:11:43+00:00","mainEntityOfPage":{"@id":"https:\/\/winfield.lestaffdigital.fr\/fr\/damon-hill-winfield-ma-donne-le-gout-de-lauto\/"},"wordCount":722,"publisher":{"@id":"https:\/\/winfield.lestaffdigital.fr\/fr\/#organization"},"image":{"@id":"https:\/\/winfield.lestaffdigital.fr\/fr\/damon-hill-winfield-ma-donne-le-gout-de-lauto\/#primaryimage"},"thumbnailUrl":"https:\/\/winfield.lestaffdigital.fr\/wp-content\/uploads\/2024\/10\/Template-Article-WRS_2023-copie.jpg","articleSection":["Non classifi\u00e9(e)"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/winfield.lestaffdigital.fr\/fr\/damon-hill-winfield-ma-donne-le-gout-de-lauto\/","url":"https:\/\/winfield.lestaffdigital.fr\/fr\/damon-hill-winfield-ma-donne-le-gout-de-lauto\/","name":"DAMON HILL : \u00ab WINFIELD M'A DONN\u00c9 LE GO\u00dbT DE L'AUTO ! \u00bb","isPartOf":{"@id":"https:\/\/winfield.lestaffdigital.fr\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/winfield.lestaffdigital.fr\/fr\/damon-hill-winfield-ma-donne-le-gout-de-lauto\/#primaryimage"},"image":{"@id":"https:\/\/winfield.lestaffdigital.fr\/fr\/damon-hill-winfield-ma-donne-le-gout-de-lauto\/#primaryimage"},"thumbnailUrl":"https:\/\/winfield.lestaffdigital.fr\/wp-content\/uploads\/2024\/10\/Template-Article-WRS_2023-copie.jpg","datePublished":"2024-10-24T09:00:38+00:00","dateModified":"2024-10-24T09:11:43+00:00","description":"En 1983, Damon Hill d\u00e9couvre la monoplace \u00e0 l'\u00e9cole Winfield, un tournant qui l'am\u00e8ne \u00e0 d\u00e9laisser la moto pour le sport automobile.","breadcrumb":{"@id":"https:\/\/winfield.lestaffdigital.fr\/fr\/damon-hill-winfield-ma-donne-le-gout-de-lauto\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/winfield.lestaffdigital.fr\/fr\/damon-hill-winfield-ma-donne-le-gout-de-lauto\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/winfield.lestaffdigital.fr\/fr\/damon-hill-winfield-ma-donne-le-gout-de-lauto\/#primaryimage","url":"https:\/\/winfield.lestaffdigital.fr\/wp-content\/uploads\/2024\/10\/Template-Article-WRS_2023-copie.jpg","contentUrl":"https:\/\/winfield.lestaffdigital.fr\/wp-content\/uploads\/2024\/10\/Template-Article-WRS_2023-copie.jpg","width":463,"height":718},{"@type":"BreadcrumbList","@id":"https:\/\/winfield.lestaffdigital.fr\/fr\/damon-hill-winfield-ma-donne-le-gout-de-lauto\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/winfield.lestaffdigital.fr\/fr\/"},{"@type":"ListItem","position":2,"name":"DAMON HILL : \u00ab WINFIELD M&rsquo;A DONN\u00c9 LE GO\u00dbT DE L&rsquo;AUTO ! \u00bb"}]},{"@type":"WebSite","@id":"https:\/\/winfield.lestaffdigital.fr\/fr\/#website","url":"https:\/\/winfield.lestaffdigital.fr\/fr\/","name":"Winfield","description":"Circuit automobile &amp; \u00c9cole de pilotage","publisher":{"@id":"https:\/\/winfield.lestaffdigital.fr\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/winfield.lestaffdigital.fr\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/winfield.lestaffdigital.fr\/fr\/#organization","name":"Winfield","url":"https:\/\/winfield.lestaffdigital.fr\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/winfield.lestaffdigital.fr\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/winfield.lestaffdigital.fr\/wp-content\/uploads\/2023\/03\/Groupe-452.png","contentUrl":"https:\/\/winfield.lestaffdigital.fr\/wp-content\/uploads\/2023\/03\/Groupe-452.png","width":186,"height":72,"caption":"Winfield"},"image":{"@id":"https:\/\/winfield.lestaffdigital.fr\/fr\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/winfield.lestaffdigital.fr\/fr\/#\/schema\/person\/866926d74c43f8fe3600a1aabdb95e7a","name":"alexis.miclo","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/fa6692f97645aafd83b38b0cad6c2a1962f7fe10d16c523b9aa454d77c43f9fa?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/fa6692f97645aafd83b38b0cad6c2a1962f7fe10d16c523b9aa454d77c43f9fa?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fa6692f97645aafd83b38b0cad6c2a1962f7fe10d16c523b9aa454d77c43f9fa?s=96&d=mm&r=g","caption":"alexis.miclo"},"url":"https:\/\/winfield.lestaffdigital.fr\/fr\/author\/alexis-miclo\/"}]}},"_links":{"self":[{"href":"https:\/\/winfield.lestaffdigital.fr\/fr\/wp-json\/wp\/v2\/posts\/6878","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/winfield.lestaffdigital.fr\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/winfield.lestaffdigital.fr\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/winfield.lestaffdigital.fr\/fr\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/winfield.lestaffdigital.fr\/fr\/wp-json\/wp\/v2\/comments?post=6878"}],"version-history":[{"count":2,"href":"https:\/\/winfield.lestaffdigital.fr\/fr\/wp-json\/wp\/v2\/posts\/6878\/revisions"}],"predecessor-version":[{"id":6880,"href":"https:\/\/winfield.lestaffdigital.fr\/fr\/wp-json\/wp\/v2\/posts\/6878\/revisions\/6880"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/winfield.lestaffdigital.fr\/fr\/wp-json\/wp\/v2\/media\/6875"}],"wp:attachment":[{"href":"https:\/\/winfield.lestaffdigital.fr\/fr\/wp-json\/wp\/v2\/media?parent=6878"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/winfield.lestaffdigital.fr\/fr\/wp-json\/wp\/v2\/categories?post=6878"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/winfield.lestaffdigital.fr\/fr\/wp-json\/wp\/v2\/tags?post=6878"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}